{"id":9242,"date":"2024-09-17T14:39:53","date_gmt":"2024-09-17T12:39:53","guid":{"rendered":"https:\/\/antcube.shop\/en\/product\/antcube-digfix-platte-30x30-xl\/"},"modified":"2026-07-10T17:44:34","modified_gmt":"2026-07-10T15:44:34","slug":"antcube-digfix-platte-30x30-xl","status":"publish","type":"product","link":"https:\/\/antcube.shop\/pt\/produto\/antcube-digfix-platte-30x30-xl\/","title":{"rendered":"ANTCUBE - Placa Digfix 30\u00d730 - XL"},"content":{"rendered":"<p><span data-text-color=\"alert\"><strong>Envio apenas poss\u00edvel via GO! dentro da Alemanha ou via palete dentro da Europa (sem ilhas)<\/strong><\/span><\/p>\n<p><strong>Dimens\u00f5es:<\/strong> 284x230x50 mm (toler\u00e2ncia de 282-285 mm)<\/p>\n<p><strong>Material:<\/strong> Digfix<\/p>\n<p><strong>Descri\u00e7\u00e3o:<\/strong> A placa Digfix, feita de material escav\u00e1vel, adapta-se perfeitamente aos nossos viveiros de formigas ANTCUBE. Pode ser utilizada tanto seca como h\u00famida. Tamb\u00e9m \u00e9 adequada para muitas esp\u00e9cies de formigas, especialmente para esp\u00e9cies que fazem ninhos na areia e em madeira (morta). Pode ser utilizado em vez de misturas de areia\/argila ou de ninhos de corti\u00e7a. Uma grande vantagem em rela\u00e7\u00e3o aos ninhos de corti\u00e7a \u00e9 que o Digfix n\u00e3o ganha bolor mesmo quando est\u00e1 h\u00famido. Isto significa que as esp\u00e9cies de formigas com uma elevada necessidade de humidade podem facilmente ser abastecidas com \u00e1gua suficiente. O Digfix tamb\u00e9m tem a vantagem de as esp\u00e9cies de formigas escavadoras n\u00e3o sujarem os vidros do seu ninho quando escavam, permitindo uma vis\u00e3o perfeita do ninho.<\/p>\n<p><strong>Nota:<\/strong> A cor natural pode variar entre o verde\/acinzentado-castanho e o castanho-terra. A tonalidade da cor n\u00e3o tem qualquer influ\u00eancia na qualidade.<br \/>\nDevido ao processo de fabrico, as dimens\u00f5es podem variar +\/- 1 mm.<\/p>","protected":false},"excerpt":{"rendered":"<p>Tamanho: <span style=\"color: #ff0000;\"><strong>XL<\/strong><\/span><\/p>","protected":false},"featured_media":9672,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"content-type":""},"product_brand":[],"product_cat":[88,87],"product_tag":[],"class_list":["post-9242","product","type-product","status-publish","has-post-thumbnail","product_cat-digfix","product_cat-nest-insets","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"aioseo_notices":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/antcube.shop\/pt\/wp-json\/wp\/v2\/product\/9242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/antcube.shop\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/antcube.shop\/pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/antcube.shop\/pt\/wp-json\/wp\/v2\/comments?post=9242"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/antcube.shop\/pt\/wp-json\/wp\/v2\/media\/9672"}],"wp:attachment":[{"href":"https:\/\/antcube.shop\/pt\/wp-json\/wp\/v2\/media?parent=9242"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/antcube.shop\/pt\/wp-json\/wp\/v2\/product_brand?post=9242"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/antcube.shop\/pt\/wp-json\/wp\/v2\/product_cat?post=9242"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/antcube.shop\/pt\/wp-json\/wp\/v2\/product_tag?post=9242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}