{"id":4734,"date":"2022-11-14T15:04:43","date_gmt":"2022-11-14T14:04:43","guid":{"rendered":"https:\/\/antcube.shop\/produkt\/rohrverbinder-glasklar-fur-32mm-t\/"},"modified":"2026-08-31T17:52:20","modified_gmt":"2026-08-31T15:52:20","slug":"rohrverbinder-glasklar-fur-32mm-t","status":"publish","type":"product","link":"https:\/\/antcube.shop\/pt\/produto\/rohrverbinder-glasklar-fur-32mm-t\/","title":{"rendered":"Conector do tubo cristalino para 32mm - T"},"content":{"rendered":"<p><strong>Dimens\u00f5es (CxLxA):<\/strong> 8,1\u00d74,0x6,0cm<br \/>\n<strong>Di\u00e2metro interior:<\/strong> 32mm<\/p>\n<p><strong>Material:<\/strong> Acr\u00edlico<\/p>\n<p><strong>Cor:<\/strong> incolor\/transparente\/claro<\/p>\n<p><strong>Conte\u00fado:<\/strong> 1 unidade.<\/p>\n<p><strong>Especifica\u00e7\u00f5es t\u00e9cnicas:<\/strong><br \/>\nConector de tubo em forma de T acr\u00edlico com di\u00e2metro de 40 mm para tubo de 32 mm.<\/p>\n<p><strong>Descri\u00e7\u00e3o:<\/strong><br \/>\nConector de tubos em acr\u00edlico transparente para liga\u00e7\u00e3o de tubos em acr\u00edlico.<\/p>\n<p><strong>Aviso:<\/strong><br \/>\nAo montar os tubos, por favor note o seguinte:<br \/>\nDevido \u00e0s propriedades materiais do acr\u00edlico, a press\u00e3o e a alavancagem devem ser evitadas a todo o custo. Se a liga\u00e7\u00e3o for dif\u00edcil, por favor ligar com movimentos de tor\u00e7\u00e3o cuidadosos e esfregar um pouco de \u00f3leo anti-quebra, se necess\u00e1rio.<\/p>","protected":false},"excerpt":{"rendered":"<p>Dimens\u00f5es (CxLxA): 6,0\u00d74,0\u00d76,0cm Di\u00e2metro interior: 32mm Material: Acr\u00edlico Cor: Incolor\/Transparente\/Claro Conte\u00fado: 1 unidade. Especifica\u00e7\u00f5es t\u00e9cnicas: Conector de tubo em forma de L acr\u00edlico di\u00e2metro 40mm para tubo de 32mm. Descri\u00e7\u00e3o: Conector de tubo feito de acr\u00edlico transparente para ligar tubos de acr\u00edlico. Nota: Ao montar os tubos, ter em aten\u00e7\u00e3o o seguinte: Devido \u00e0s propriedades do material acr\u00edlico, a press\u00e3o e a alavanca devem [...]","protected":false},"featured_media":4896,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"content-type":"","_monsterinsights_skip_tracking":false},"product_brand":[],"product_cat":[345],"product_tag":[],"class_list":["post-4734","product","type-product","status-publish","has-post-thumbnail","product_cat-pipe-connectors","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"aioseo_notices":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/antcube.shop\/pt\/wp-json\/wp\/v2\/product\/4734","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/antcube.shop\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/antcube.shop\/pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/antcube.shop\/pt\/wp-json\/wp\/v2\/comments?post=4734"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/antcube.shop\/pt\/wp-json\/wp\/v2\/media\/4896"}],"wp:attachment":[{"href":"https:\/\/antcube.shop\/pt\/wp-json\/wp\/v2\/media?parent=4734"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/antcube.shop\/pt\/wp-json\/wp\/v2\/product_brand?post=4734"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/antcube.shop\/pt\/wp-json\/wp\/v2\/product_cat?post=4734"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/antcube.shop\/pt\/wp-json\/wp\/v2\/product_tag?post=4734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}