{"id":11499,"date":"2025-04-25T15:12:26","date_gmt":"2025-04-25T13:12:26","guid":{"rendered":"https:\/\/antcube.shop\/en\/product\/poster-weberameisen-oecophylla-lebensweise-100x70\/"},"modified":"2026-01-12T12:41:38","modified_gmt":"2026-01-12T11:41:38","slug":"cartaz-formigas-tecelas-oecophylla-modo-de-vida-100x70","status":"publish","type":"product","link":"https:\/\/antcube.shop\/pt\/produto\/cartaz-formigas-tecelas-oecophylla-modo-de-vida-100x70\/","title":{"rendered":"Cartaz - Formigas tecel\u00e3s - Modo de vida Oecophylla - 100\u00d770"},"content":{"rendered":"<p>Formigas tecel\u00e3s - Modo de vida Oecophylla - Cartaz sobre formigas e material did\u00e1tico para escolas e jardins-de-inf\u00e2ncia.<\/p>\n<p><strong>Descri\u00e7\u00e3o dispon\u00edvel em alem\u00e3o, ingl\u00eas, espanhol e franc\u00eas<\/strong><\/p>\n<p><strong>Dimens\u00f5es:<\/strong> 100\u00d770 cm<\/p>\n<p><strong>Material:<\/strong> Papel de l\u00e1tex<br \/>\nEste papel \u00e9 imperme\u00e1vel, limp\u00e1vel, resistente, amigo do ambiente, uma vez que n\u00e3o cont\u00e9m solventes nocivos para o ambiente e produz uma qualidade de impress\u00e3o brilhante.<\/p>\n<p><strong>Descri\u00e7\u00e3o:<\/strong> Este cartaz apresenta uma vis\u00e3o geral do modo de vida e da constru\u00e7\u00e3o de ninhos de Oecophylla, a esp\u00e9cie de formiga tecel\u00e3 da \u00c1sia, \u00c1frica e Austr\u00e1lia.<\/p>\n<p><strong>Importante - informa\u00e7\u00f5es adicionais:<\/strong> <a href=\"https:\/\/www.ants.de\/link\/1003\">Aqui<\/a> encontrar\u00e1 uma descri\u00e7\u00e3o pormenorizada das cenas individuais no cartaz. Estes n\u00e3o est\u00e3o inclu\u00eddos, mas podem ser acedidos e impressos separadamente atrav\u00e9s da seguinte liga\u00e7\u00e3o. <a href=\"https:\/\/www.ants.de\/link\/1003\">https:\/\/www.ants.de\/link\/1003<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Formigas tecel\u00e3s - Modo de vida Oecophylla - Cartaz sobre formigas e material did\u00e1tico para escolas e jardins de inf\u00e2ncia. Descri\u00e7\u00e3o dispon\u00edvel em alem\u00e3o, ingl\u00eas, espanhol e franc\u00eas Dimens\u00f5es: 100x70 cm Material: Papel de l\u00e1tex Este papel \u00e9 imperme\u00e1vel, limp\u00e1vel, resistente, amigo do ambiente, pois n\u00e3o cont\u00e9m solventes nocivos para o ambiente e produz uma qualidade de impress\u00e3o brilhante. Descri\u00e7\u00e3o: Este cartaz oferece","protected":false},"featured_media":11402,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"content-type":""},"product_brand":[484],"product_cat":[500],"product_tag":[],"class_list":["post-11499","product","type-product","status-publish","has-post-thumbnail","product_brand-antcube","product_cat-ant-posters-and-teaching-aids","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"aioseo_notices":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/antcube.shop\/pt\/wp-json\/wp\/v2\/product\/11499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/antcube.shop\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/antcube.shop\/pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/antcube.shop\/pt\/wp-json\/wp\/v2\/comments?post=11499"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/antcube.shop\/pt\/wp-json\/wp\/v2\/media\/11402"}],"wp:attachment":[{"href":"https:\/\/antcube.shop\/pt\/wp-json\/wp\/v2\/media?parent=11499"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/antcube.shop\/pt\/wp-json\/wp\/v2\/product_brand?post=11499"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/antcube.shop\/pt\/wp-json\/wp\/v2\/product_cat?post=11499"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/antcube.shop\/pt\/wp-json\/wp\/v2\/product_tag?post=11499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}