{"id":4175,"date":"2022-03-14T17:24:15","date_gmt":"2022-03-14T16:24:15","guid":{"rendered":"https:\/\/antcube.shop\/produkt\/candy-ant-snack-20g\/"},"modified":"2026-07-13T10:09:10","modified_gmt":"2026-07-13T08:09:10","slug":"caramella-ant-snack-20g","status":"publish","type":"product","link":"https:\/\/antcube.shop\/it\/prodotto\/caramella-ant-snack-20g\/","title":{"rendered":"Candy Ant Snack - 20g"},"content":{"rendered":"<p><strong>Contenuto:<\/strong><br \/>\n20g<\/p>\n<p><strong>Descrizione:<\/strong><br \/>\nQuesto \u00e8 un prodotto naturale puro. Il nostro Candy Ant Snack, fatto da Acheta domesticus coltivata biologicamente, ricoperto di miele biologico.<br \/>\nFacilmente digeribile. Grazie alle proteine di alta qualit\u00e0, \u00e8 un alimento quasi completo (sostituisce miele\/zucchero e proteine) per la maggior parte delle specie di formiche come Lasius sp., Camponotus sp. o Messor sp. ecc. Le formiche lo adorano. Non sostituisce l'acqua fresca necessaria alle formiche. Non sostituisce nemmeno il bisogno di proteine vive, come i piccoli insetti.<\/p>\n<p>Questo mangime supplementare \u00e8 pieno di proteine potenti che contengono circa 50% di pura proteina naturale.<br \/>\nInoltre, il prodotto \u00e8 stato alimentato con rifiuti vegetali organici senza pesticidi, il che ha un alto valore ecologico, dato che viene utilizzata meno energia e acqua nella sua produzione.<\/p>\n<p>Il valore aggiunto per tutti gli amanti delle formiche, \u00e8 la combinazione di proteine naturali e il rivestimento con miele naturale. Le formiche amano e hanno bisogno di questo per un buon sviluppo della covata e una crescita sana della colonia.<\/p>\n<p><strong>Applicazione:<\/strong><br \/>\nPer l'alimentazione, Candy Ant Snack dovrebbe essere diviso in porzioni pi\u00f9 piccole o sciolto in acqua.<\/p>\n<p><strong>Contiene:<\/strong><br \/>\nAcheta domesticus essiccata naturalmente e ricoperta di miele biologico. Non destinato al consumo umano. Solo per le formiche.<br \/>\nRapporto di miscelazione approssimativo 70% Acheta domesticus e 30% miele.<\/p>\n<p><strong>Stoccaggio:<\/strong><br \/>\nRichiudibile. Conservare in un luogo buio, fresco e asciutto.<\/p>\n<p><strong>Nota:<\/strong><br \/>\nCibo supplementare per le formiche.<br \/>\nSi prega di fare riferimento al foglietto illustrativo per la composizione, gli ingredienti analitici, la data di scadenza e il numero di lotto.<\/p>\n<p>Numero verde per informazioni +49 30 439703870<\/p>\n<p>Ispettorato veterinario e alimentare responsabile:<br \/>\nUfficio veterinario Steglitz<br \/>\nVia K\u00f6nigin-Luise 92<br \/>\n14195 Berlino<\/p>","protected":false},"excerpt":{"rendered":"<p>Cibo supplementare<\/p>","protected":false},"featured_media":4182,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"content-type":""},"product_brand":[],"product_cat":[116,115],"product_tag":[],"class_list":["post-4175","product","type-product","status-publish","has-post-thumbnail","product_cat-food","product_cat-food-and-feeding","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"aioseo_notices":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/antcube.shop\/it\/wp-json\/wp\/v2\/product\/4175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/antcube.shop\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/antcube.shop\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/antcube.shop\/it\/wp-json\/wp\/v2\/comments?post=4175"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/antcube.shop\/it\/wp-json\/wp\/v2\/media\/4182"}],"wp:attachment":[{"href":"https:\/\/antcube.shop\/it\/wp-json\/wp\/v2\/media?parent=4175"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/antcube.shop\/it\/wp-json\/wp\/v2\/product_brand?post=4175"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/antcube.shop\/it\/wp-json\/wp\/v2\/product_cat?post=4175"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/antcube.shop\/it\/wp-json\/wp\/v2\/product_tag?post=4175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}