{"id":4145,"date":"2022-02-14T15:54:25","date_gmt":"2022-02-14T14:54:25","guid":{"rendered":"https:\/\/antcube.shop\/produkt\/ant-nuggets-20g\/"},"modified":"2026-07-15T17:48:16","modified_gmt":"2026-07-15T15:48:16","slug":"crocchette-di-formica-20g","status":"publish","type":"product","link":"https:\/\/antcube.shop\/it\/prodotto\/crocchette-di-formica-20g\/","title":{"rendered":"Pepite di formica - 20g"},"content":{"rendered":"<p><strong>Contenuto:<\/strong><br \/>\n20g<\/p>\n<p><strong>Descrizione:<\/strong><br \/>\nQuesto \u00e8 un prodotto naturale puro. Le nostre pepite di formica, sono state accuratamente raccolte nella natura selvaggia della Bulgaria dagli apicoltori. Facile digestione grazie alla fermentazione naturale. Grazie alle proteine di alta qualit\u00e0 \u00e8 un alimento quasi completo (sostituisce il miele\/zucchero e le proteine) per la maggior parte delle specie di formiche formicoidi come Lasius sp., Camponotus sp. o Messor sp. e anche le formiche tagliafoglie lo amano. Non sostituisce l'acqua dolce di cui le formiche hanno bisogno. Non sostituisce nemmeno il bisogno di proteine vive, come i piccoli insetti.<\/p>\n<p><strong>Applicazione:<\/strong><br \/>\nPer l'alimentazione, Ant Nuggets dovrebbe essere diviso in porzioni pi\u00f9 piccole o sciolto in acqua.<\/p>\n<p><strong>Contiene:<\/strong><br \/>\n100% polline di fiori fermentato naturalmente. Non destinato al consumo umano. Solo per le formiche.<\/p>\n<p><strong>Stoccaggio:<\/strong><br \/>\nRichiudibile. Conservare in un luogo buio, fresco e asciutto.<\/p>\n<p><strong>Nota:<\/strong><br \/>\nCibo supplementare per le formiche.<br \/>\nSi prega di fare riferimento al foglietto illustrativo per la composizione, gli ingredienti analitici, la data di scadenza e il numero di lotto.<\/p>\n<p>Numero verde per informazioni +49 30 439703870<\/p>\n<p>Ispettorato veterinario e alimentare responsabile:<br \/>\nUfficio veterinario Steglitz<br \/>\nVia K\u00f6nigin-Luise 92<br \/>\n14195 Berlino<\/p>","protected":false},"excerpt":{"rendered":"<p>Cibo supplementare<\/p>","protected":false},"featured_media":4149,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"content-type":""},"product_brand":[],"product_cat":[116,115],"product_tag":[],"class_list":["post-4145","product","type-product","status-publish","has-post-thumbnail","product_cat-food","product_cat-food-and-feeding","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"aioseo_notices":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/antcube.shop\/it\/wp-json\/wp\/v2\/product\/4145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/antcube.shop\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/antcube.shop\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/antcube.shop\/it\/wp-json\/wp\/v2\/comments?post=4145"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/antcube.shop\/it\/wp-json\/wp\/v2\/media\/4149"}],"wp:attachment":[{"href":"https:\/\/antcube.shop\/it\/wp-json\/wp\/v2\/media?parent=4145"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/antcube.shop\/it\/wp-json\/wp\/v2\/product_brand?post=4145"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/antcube.shop\/it\/wp-json\/wp\/v2\/product_cat?post=4145"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/antcube.shop\/it\/wp-json\/wp\/v2\/product_tag?post=4145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}