{"id":4609,"date":"2022-11-01T18:08:27","date_gmt":"2022-11-01T17:08:27","guid":{"rendered":"https:\/\/antcube.shop\/produkt\/ameisenarena-abdeckung-30x30\/"},"modified":"2026-07-15T11:17:32","modified_gmt":"2026-07-15T09:17:32","slug":"ameisenarena-abdeckung-30x30","status":"publish","type":"product","link":"https:\/\/antcube.shop\/fr\/produit\/ameisenarena-abdeckung-30x30\/","title":{"rendered":"Couverture de l'ar\u00e8ne des fourmis 30\u00d730"},"content":{"rendered":"<p><strong>Dimensions (LxlxH) :<\/strong> 30x30x0,4 cm<\/p>\n<p><strong>Mat\u00e9riau :<\/strong> verre flott\u00e9<\/p>\n<p><strong>Couleur :<\/strong> limpide \/ transparent<\/p>\n<p><strong>Contenu :<\/strong><br \/>\n1x couverture de l'ar\u00e8ne des fourmis<br \/>\n1x points de fixation \u00e0 4 pcs.<\/p>\n<p><strong>Description :<\/strong><br \/>\nCouverture en verre pour la fourmili\u00e8re comme protection contre la fuite.<\/p>\n<p><strong>Application :<\/strong><br \/>\nLe couvercle de la fourmili\u00e8re en verre est plac\u00e9 sur une fourmili\u00e8re et sert aussi imm\u00e9diatement \u00e0 la r\u00e9gulation du climat.<br \/>\nDiff\u00e9rents modules de contr\u00f4le climatique peuvent \u00eatre ins\u00e9r\u00e9s dans les ouvertures de 50 mm, par exemple des grilles de ventilation, un \u00e9clairage ou une humidification.<br \/>\nPour emp\u00eacher les fourmis de s'\u00e9chapper par les ouvertures, il faut appliquer une protection contre les fuites (huile, poudre ou vernis) sur la face inf\u00e9rieure autour des trous.<\/p>\n<p><strong>Avis :<\/strong><br \/>\nL'article \u00e9tant en verre et donc susceptible de se briser, il doit \u00eatre manipul\u00e9 avec beaucoup de pr\u00e9cautions.<\/p>","protected":false},"excerpt":{"rendered":"<p>Dimensions (LxlxH) : 30x30x0,4 cm Mat\u00e9riau : verre flott\u00e9 Couleur : cristal clair \/ transparent Contenu : 1x couvercle de fourmili\u00e8re 1x points de fixation \u00e0 4 pcs. Description : Couvercle en verre pour l'ar\u00e8ne \u00e0 fourmis comme protection de fuite. Application : Le couvercle en verre pour la fourmili\u00e8re est plac\u00e9 sur la fourmili\u00e8re et sert imm\u00e9diatement de protection contre la fuite.","protected":false},"featured_media":4800,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"content-type":""},"product_brand":[],"product_cat":[92,91],"product_tag":[],"class_list":["post-4609","product","type-product","status-publish","has-post-thumbnail","product_cat-arena-cover","product_cat-formicarium-modules","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"aioseo_notices":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/antcube.shop\/fr\/wp-json\/wp\/v2\/product\/4609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/antcube.shop\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/antcube.shop\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/antcube.shop\/fr\/wp-json\/wp\/v2\/comments?post=4609"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/antcube.shop\/fr\/wp-json\/wp\/v2\/media\/4800"}],"wp:attachment":[{"href":"https:\/\/antcube.shop\/fr\/wp-json\/wp\/v2\/media?parent=4609"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/antcube.shop\/fr\/wp-json\/wp\/v2\/product_brand?post=4609"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/antcube.shop\/fr\/wp-json\/wp\/v2\/product_cat?post=4609"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/antcube.shop\/fr\/wp-json\/wp\/v2\/product_tag?post=4609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}