{"id":2838,"date":"2021-10-13T18:37:02","date_gmt":"2021-10-13T16:37:02","guid":{"rendered":"https:\/\/antcube.shop\/produkt\/bodengrund-wiese-1-kg\/"},"modified":"2026-07-14T14:08:46","modified_gmt":"2026-07-14T12:08:46","slug":"bodengrund-wiese-1-kg","status":"publish","type":"product","link":"https:\/\/antcube.shop\/de\/produkt\/bodengrund-wiese-1-kg\/","title":{"rendered":"Substrat - Wiese - 1 Kg"},"content":{"rendered":"<p><strong>Inhalt:<\/strong> 1 kg<\/p>\n<p><strong>Material:<\/strong> Sand, Torf, Humus, Ton, gesiebt<\/p>\n<p><strong>Farbe:<\/strong> braun, beige<\/p>\n<p><strong>Beschreibung:<\/strong> Dieser Wiesenboden besteht haupts\u00e4chlich aus Sand mit leichtem Tonanteil und nat\u00fcrlichen Faserkomponenten.<br \/>\nEs ist ein nat\u00fcrlicher Boden f\u00fcr alle Ameisenarten, die auf Feldern oder Wiesen leben.<\/p>\n<p><strong>Anwendung:<\/strong> W\u00fchlbare Erde kann f\u00fcr Nest- und Arenabereiche verwendet werden!<\/p>\n<p><strong>Anmerkung:<\/strong> Da es sich um ein reines Naturprodukt handelt, kann es kleine Unterschiede in Farbe und Struktur geben, die wir nicht beeinflussen k\u00f6nnen.<\/p>\n<p><strong>Das ist wichtig:<\/strong> Bitte befeuchten Sie das Substrat vor der Verwendung, damit sich die Mischung verbinden und einen festen Halt im Ameisenbau entwickeln kann. Au\u00dferdem kann ein zu trockenes und staubiges Substrat dazu f\u00fchren, dass die Atemwege der Ameisen verstopft werden und die Tiere im schlimmsten Fall ersticken.<\/p>","protected":false},"excerpt":{"rendered":"<p>Nat\u00fcrlicher besonderer Lebensraum Boden\/Substrat<\/p>","protected":false},"featured_media":5506,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"content-type":""},"product_brand":[],"product_cat":[96],"product_tag":[],"class_list":["post-2838","product","type-product","status-publish","has-post-thumbnail","product_cat-soil","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"aioseo_notices":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/antcube.shop\/de\/wp-json\/wp\/v2\/product\/2838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/antcube.shop\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/antcube.shop\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/antcube.shop\/de\/wp-json\/wp\/v2\/comments?post=2838"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/antcube.shop\/de\/wp-json\/wp\/v2\/media\/5506"}],"wp:attachment":[{"href":"https:\/\/antcube.shop\/de\/wp-json\/wp\/v2\/media?parent=2838"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/antcube.shop\/de\/wp-json\/wp\/v2\/product_brand?post=2838"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/antcube.shop\/de\/wp-json\/wp\/v2\/product_cat?post=2838"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/antcube.shop\/de\/wp-json\/wp\/v2\/product_tag?post=2838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}